{"id":3614,"date":"2022-01-11T19:05:04","date_gmt":"2022-01-11T19:05:04","guid":{"rendered":"https:\/\/amigurumireceitas.com\/?p=3614"},"modified":"2022-06-07T12:27:43","modified_gmt":"2022-06-07T11:27:43","slug":"paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis","status":"publish","type":"post","link":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/","title":{"rendered":"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3616 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"600\" height=\"800\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis.jpg 600w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-225x300.jpg 225w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-150x200.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\nHola a todos amigos,<br \/>\nHoy os traigo un patr\u00f3n de amigurumi muy especial. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El patr\u00f3n de amigurumi gratuito es un poco largo, por lo que puede no ser ideal para principiantes. Patr\u00f3n de amigurumi Minion Rush, gracias a las instrucciones detalladas <strong>paso a paso<\/strong> del patr\u00f3n y las im\u00e1genes que explican c\u00f3mo hacerlo, a los amantes de los amigurumis les encantar\u00e1 este <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/amigurumireceitas.com\/es\/category\/personajes-de-cuento-de-hadas\/\">patr\u00f3n<\/a><\/span><\/strong>. Puedes completar el patr\u00f3n <a href=\"https:\/\/amigurumireceitas.com\/es\/category\/navidad\/\"><strong><span style=\"color: #3366ff;\">amigurumis<\/span><\/strong><\/a> crochet minion rush y regal\u00e1rselo a tus hijos. Traduje el patr\u00f3n yo mismo, por lo que puede haber errores menores, puede informarnos a nosotros o al propietario del patr\u00f3n. Ahora os dejo en paz con el patr\u00f3n amigurumi crochet minion rush. Est\u00e9n atentos para m\u00e1s patrones de crochet <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/amigurumireceitas.com\/es\/category\/munecas\/\">amigurumi gratis<\/a><\/span><\/strong>.<\/p>\n<h2><span style=\"color: #cc99ff;\">Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis<\/span><\/h2>\n<p><strong>Dise\u00f1ador:<\/strong> <span style=\"color: #cc99ff;\">@cozypuppet<\/span><\/p>\n<p>El Minion mide aproximadamente 40 cm de alto y 19 cm de di\u00e1metro.<\/p>\n<h3><span style=\"color: #cc99ff;\">Abreviaturas<\/span><\/h3>\n<p><span style=\"color: #ff0000;\">AM<\/span> \u2013 anillo m\u00e1gico<br \/>\n<span style=\"color: #ff0000;\">Pb<\/span> \u2013 punto bajo<br \/>\n<span style=\"color: #ff0000;\">Aum<\/span>&#8211; aumento en punto bajo<br \/>\n<span style=\"color: #ff0000;\">Dism<\/span>&#8211; Disminuci\u00f2n<br \/>\n<span style=\"color: #ff0000;\">Pvd<\/span> \u2013 punto vareta doble<br \/>\n<span style=\"color: #ff0000;\">Pt<\/span>&#8211; Punto<br \/>\n<span style=\"color: #ff0000;\">Pa<\/span> \u2013 punto alto o punto vareta<br \/>\n<span style=\"color: #ff0000;\">Mpa<\/span> \u2013 medio punto alto o punto media vareta<br \/>\n<span style=\"color: #ff0000;\">Pc<\/span>&#8211; punto enano, punto raso<br \/>\n<span style=\"color: #ff0000;\">Cad<\/span> \u2013 cadeneta<br \/>\n<span style=\"color: #ff0000;\">FLO<\/span>&#8211; medio punto o punto bajo canal\u00e9 tomando s\u00f2lo la hebra de adelante<br \/>\n<span style=\"color: #ff0000;\">BLO<\/span>&#8211; medio punto o punto bajo canal\u00e9 tomando s\u00f2lo la hebra de atras o punto bajo por backloop<br \/>\n<span style=\"color: #ff0000;\">BO<\/span>&#8211; puntada de gancadillo bobble<br \/>\n<span style=\"color: #ff0000;\">Bucles de aire<\/span>&#8211; (<strong>air loops<\/strong>) (Haz <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/www.youtube.com\/watch?v=B11EsyqrjWg&amp;ab_channel=CrochetingwithIrinaBulanova\">clic<\/a><\/span><\/strong> en el enlace para ver c\u00f3mo se hace)<br \/>\n<span style=\"color: #ff0000;\">Lazo de elevaci\u00f3n<\/span>&#8211; (<strong>lifting loop<\/strong>) (Haz <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/www.youtube.com\/watch?v=BIWmiBvRsDM&amp;ab_channel=%D0%92%D1%8F%D0%B6%D0%B5%D0%BC%D0%B2%D0%BC%D0%B5%D1%81%D1%82%D0%B5VZVM.RU%D0%A3%D1%80%D0%BE%D0%BA%D0%B8%D0%B2%D1%8F%D0%B7%D0%B0%D0%BD%D0%B8%D1%8F%D0%B4%D0%BB%D1%8F%D0%BD%D0%B0%D1%87%D0%B8%D0%BD%D0%B0%D1%8E%D1%89%D0%B8%D1%85\">clic<\/a><\/span><\/strong> en el enlace para ver c\u00f3mo se hace)<\/p>\n<h3><span style=\"color: #cc99ff;\">Materiales<\/span><\/h3>\n<p>Jeans YarnArt<br \/>\n17 (jeans oscuros)- 1 ovillo<br \/>\n49 (gris claro)- 1 ovillo<br \/>\n88 (amarillo p\u00e1lido)- 2 ovillos<br \/>\n62 (blanco)- 1 ovillo<br \/>\n53 (negro)- 1 ovillo<br \/>\nBlanco, negro y gris, por supuesto, necesitas un poco. Fieltro s\u00f3lido de 1 mm en colores blanco, negro, rojo y azul (a juego con el color del mono). Relleno (pelusa sint\u00e9tica, sinteshar). Dado que el hilo es delgado y el volumen es grande, es muy importante usar un relleno de calidad para que el empaque sea uniforme. Alambre para el armaz\u00f3n del brazo, cinta de enmascarar o cinta aislante. Ojos en una montura segura. Us\u00e9 un di\u00e1metro de 10 mm, pero at\u00e9 el iris con hilo marr\u00f3n para aumentar el di\u00e1metro a 18-20 mm. pl\u00e1stico para suelas, botella de pl\u00e1stico para vasos. Agujas para coser piezas, alfileres para fijar piezas y probar, tijeras, pegamento Moment gel.<br \/>\nDos botones para mono. Cintur\u00f3n o cinta regular para anteojos (solo puede atar el cord\u00f3n). Y casi me olvido de la herramienta m\u00e1s importante: el gancho de 3 mm.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3619 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello-2.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"586\" height=\"184\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello-2.jpg 586w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello-2-300x94.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello-2-150x47.jpg 150w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Piernas<\/span><\/h3>\n<p>Comenzamos a tejer con hilo negro de las botas, el ganchillo es de 3 mm.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. recogemos una cadena 12 bucles de aire<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. comenzamos a tejer desde el 3er bucle desde el gancho 9 pb, 4 pb en un bucle, en el otro lado de la cadena 8 pb, aum (24)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. marcar el comienzo de la fila con un marcador, tejer en espiral aum, 5 pb, 2 mpa, 2 pa, 4 aum de pa, 2 pa, 2 mpa, 5 pb, aum (30)<br \/>\n<span style=\"color: #ff0000;\">4 hilera<\/span>. 1 pb, aum, 13 pb, 2 aum, 12 pb, aum (34)<br \/>\nHacemos un c\u00edrculo en la suela resultante en papel para cortar las plantillas en el futuro.<br \/>\n<span style=\"color: #ff0000;\">5 hilera<\/span>. 34 pb para la pared trasera (34)<br \/>\n<span style=\"color: #ff0000;\">6 hilera<\/span>. 34 pb (34)<br \/>\n<span style=\"color: #ff0000;\">7 hilera<\/span>. 8 pb, 2 dism, 12 pb, 2 dism, 6 pb (30)<br \/>\n<span style=\"color: #ff0000;\">8 hilera<\/span>. 10 pb, 6 dism, 8 pb (24)<br \/>\n<span style=\"color: #ff0000;\">9 hilera<\/span>. 24 pb (24)<br \/>\nRecorte la plantilla del pl\u00e1stico de acuerdo con el patr\u00f3n descrito anteriormente. Lo insertamos en el maletero, lo ajustamos a la medida, si es necesario. La plantilla no debe ser m\u00e1s grande que la suela para que la bota no se doble. Como material, puede tomar tapas, tablas de cortar delgadas. A menudo uso descuentos innecesarios y tarjetas acumulativas de tiendas. Comenzamos a completar el detalle.<br \/>\n<span style=\"color: #ff0000;\">10 hilera<\/span>. marque el centro de la parte delantera de la bota. Con respecto a ella, hacemos disminuciones 9 pb, 4 dism, 7 pb (20)<br \/>\nDebido a la diferente densidad del tejido o hilo aqu\u00ed y en el futuro, es posible que tenga una ubicaci\u00f3n diferente de dism \/ aum en relaci\u00f3n con el comienzo de la fila. Conc\u00e9ntrate en tus marcadores.<br \/>\n<span style=\"color: #ff0000;\">11 hilera<\/span>. 7 pb, 4 dism, 5 pb (16)<br \/>\n<span style=\"color: #ff0000;\">12 hilera<\/span>. 16 pb (16)<br \/>\nSujetamos el hilo, dejamos una punta larga para coser. Tejemos dos partes.<br \/>\nSi desea que el minion se mantenga de pie por s\u00ed solo y ya trabaje con marcos de alambre, puede usar alambre en las piernas. Con sus grandes dimensiones, el juguete pesa solo 700 gramos y bien puede sostenerse sobre sus propios pies. Inserte el alambre en esta etapa, luego p\u00e1selo por el comienzo del tejido de los pantalones.<br \/>\nTomamos hilo azul, gancho de 3 mm. Tejemos los pantalones del mono.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. 6 pb en AM (6)<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. 6 aum (12)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. (1 pb, aum) * 6 veces (18)<br \/>\n<span style=\"color: #ff0000;\">4 hilera<\/span>. (2 pb, aum) * 6 veces (24)<br \/>\n<span style=\"color: #ff0000;\">5 hilera<\/span>. 24 pb detr\u00e1s de la pared trasera (24)<br \/>\n<span style=\"color: #ff0000;\">6 hilera<\/span>. 24 pb (24)<br \/>\n<span style=\"color: #ff0000;\">7 hilera<\/span>. (3 pb, aum) * 6 veces (30)<br \/>\n<span style=\"color: #ff0000;\">8-10 hileras<\/span>. 30 pb (30)<br \/>\n<span style=\"color: #ff0000;\">11 hilera<\/span>. (4 pb, aum) * 6 veces (36)<br \/>\n<span style=\"color: #ff0000;\">12 hilera<\/span>. 36 pb (36)<br \/>\nCierra el tejido, deja una punta larga para coser. Tejemos 2 detalles.<br \/>\nCoser las botas a las piernas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3622 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-piernas.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"799\" height=\"192\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-piernas.jpg 799w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-piernas-300x72.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-piernas-768x185.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-piernas-150x36.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-piernas-750x180.jpg 750w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Brazos<\/span><\/h3>\n<p>Comenzamos a tejer con los dedos. Hilo negro, ganchillo 3 mm.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. 6 pb en AM (6)<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. 6 aum (12)<br \/>\n<span style=\"color: #ff0000;\">3-4 hileras<\/span>. 12 pb (12)<br \/>\n<span style=\"color: #ff0000;\">5 hilera<\/span>. (3 pb, aum)* 3 veces (15)<br \/>\n<span style=\"color: #ff0000;\">6-11 hileras<\/span>. 15 pb (15)<br \/>\nTejemos tres elementos. No rompemos el hilo en el tercero. Primero, conecte dos dedos.<br \/>\n<span style=\"color: #ff0000;\">12 hilera<\/span>. 8 pb, adjuntar el segundo dedo, tejer 14 pb en eso, corbata 7 pb en la primera (30)<br \/>\n<span style=\"color: #ff0000;\">13 hilera<\/span>. 30 pb (30)<br \/>\n<span style=\"color: #ff0000;\">14 hilera<\/span>. unimos el tercer dedo 4 pb, los siguientes 7 pb tejemos juntos con 7 pb del tercer dedo, tejemos 19 pb (30)<br \/>\n<span style=\"color: #ff0000;\">15 hilera<\/span>. atamos por el per\u00edmetro junto con los 8 pb restantes del tercer dedo (31)<br \/>\n<span style=\"color: #ff0000;\">16 hilera<\/span>. 29 pb, dism (30)<br \/>\nHacer un marco de alambre. Estoy usando alambre de 1 mm. Cortar unos 60 cm. Formar tres dedos de 5 cm de largo. Por seguridad y fuerza, envolvemos cada dedo y cepillamos con cinta adhesiva o cinta aislante. Inserte el marco. Nos llenamos los dedos.<br \/>\n<span style=\"color: #ff0000;\">17 hilera<\/span>. (3 pb, dism)* 6 veces (24)<br \/>\n<span style=\"color: #ff0000;\">18 hilera<\/span>. (2 pb, dism)* 6 veces (18)<br \/>\n<span style=\"color: #ff0000;\">19 hilera<\/span>. 18 pb (18)<br \/>\nRellenamos el pincel.<br \/>\nAdem\u00e1s, son posibles dos opciones:<br \/>\n\u2013 Puede tejer inmediatamente el pu\u00f1o del guante y luego levantar los lazos de la fila 19 para tejer la mano;<br \/>\n\u2013 Cambias a tejer en amarillo, y tejes el pu\u00f1o por separado y coses (mi versi\u00f3n).<br \/>\n<span style=\"color: #ff0000;\">20-44 hileras<\/span>. cambia el color a amarillo y teje 18 pb (18), rellena poco a poco, no mucho.<br \/>\nCerramos el tejido, ocultamos las puntas. Tejemos dos elementos.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3625 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-brazos.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"785\" height=\"185\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-brazos.jpg 785w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-brazos-300x71.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-brazos-768x181.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-brazos-150x35.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-brazos-750x177.jpg 750w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><br \/>\n\u2800<br \/>\n<span style=\"color: #cc99ff;\">Brazalete<\/span><\/h3>\n<p>Tejemos con hilo negro, ganchillo de 3 mm.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. comenzar con una cadena de 19 bucles de aire. Luego tejemos desde el tercer bucle desde el gancho con incrementos, como en el tejido en espiral, pero solo en filas rotativas.<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. 1 pb, aum, (2 pb, aum)* 5 veces (24)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. lazo de elevaci\u00f3n, 2 pb, aum, (3 pb, aum)* 5 veces (30)<br \/>\n<span style=\"color: #ff0000;\">4 hilera<\/span>. lazo de elevaci\u00f3n, 29 pb (30)<br \/>\nTejemos dos partes. Dejamos la punta larga para coser. Ponemos el mango, cosimos en un anillo, cosimos en la fila 19. Eso es todo por ahora. La siguiente etapa ser\u00e1 la m\u00e1s larga, ya que el torso ya estar\u00e1 tejido. La parte inferior del mono y el cuerpo est\u00e1n tejidos en una sola pieza. Coser las piernas, tejer las asas y hablar del peinado.<\/p>\n<h3><span style=\"color: #cc99ff;\">Cuerpo<\/span><\/h3>\n<p>Comenzamos a tejer con hilo azul, ganchillo de 3 mm.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. 7 pb en AM (7)<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. 7 aum (14)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. (1 pb, aum)*7 veces (21)<br \/>\n<span style=\"color: #ff0000;\">4 hilera<\/span>. (2 pb, aum)*7 veces (28)<br \/>\n<span style=\"color: #ff0000;\">5 hilera<\/span>. (3 pb, aum)*7 veces (35)<br \/>\n<span style=\"color: #ff0000;\">6 hilera<\/span>. (4 pb, aum)*7 veces (42)<br \/>\n<span style=\"color: #ff0000;\">7 hilera<\/span>. (5 pb, aum)*7 veces (49)<br \/>\n<span style=\"color: #ff0000;\">8 hilera<\/span>. (6 pb, aum)*7 veces (56)<br \/>\n<span style=\"color: #ff0000;\">9 hilera<\/span>. (7 pb, aum)*7 veces (63)<br \/>\n<span style=\"color: #ff0000;\">10 hilera<\/span>. (8 pb, aum)*7 veces (70)<br \/>\n<span style=\"color: #ff0000;\">11 hilera<\/span>. (9 pb, aum)*7 veces (77)<br \/>\n<span style=\"color: #ff0000;\">12 hilera<\/span>. (10 pb, aum)*7 veces (84)<br \/>\n<span style=\"color: #ff0000;\">13 hilera<\/span>. (11 pb, aum)*7 veces (91)<br \/>\n<span style=\"color: #ff0000;\">14 hilera<\/span>. (12 pb, aum)*7 veces (98)<br \/>\n<span style=\"color: #ff0000;\">15 hilera<\/span>. (13 pb, aum)*7 veces (105)<br \/>\n<span style=\"color: #ff0000;\">16 hilera<\/span>. (14 pb, aum)*7 veces (112)<br \/>\n<span style=\"color: #ff0000;\">17 hilera<\/span>. (15 pb, aum)*7 veces (119)<br \/>\n<span style=\"color: #ff0000;\">18 hilera<\/span>. (16 pb, aum)*7 veces (126)<br \/>\n<span style=\"color: #ff0000;\">19-22 hileras<\/span>. 126 pb (126)<br \/>\nEn esta etapa, deber\u00e1 coser las piernas. Tengo m\u00e1s tejidos en la foto en este punto, pero es un inconveniente coser as\u00ed. Las piernas est\u00e1n ubicadas cerca del centro de los minions. Las puntas de las botas generalmente est\u00e1n hacia afuera, pero puede establecer cualquier posici\u00f3n. Rellene bien las piernas. Despu\u00e9s de coser, marque el centro del frente. Como en el futuro necesitaremos un bolsillo en el frente, tej\u00ed 50 pb debajo para las paredes traseras para que sea m\u00e1s f\u00e1cil levantar los bucles. En consecuencia, reserve 25 puntos desde el marcador central hacia la izquierda y la derecha.<br \/>\n<span style=\"color: #ff0000;\">23 hilera<\/span>. 5 pb, 50 pb para las paredes traseras, 71 pb (126)<br \/>\n<span style=\"color: #ff0000;\">24-29 hileras<\/span>. 126 pb (126)<br \/>\n<span style=\"color: #ff0000;\">30 hilera<\/span>. cambiar el color del hilo a amarillo (esto debe hacerse en el centro del frente para que la transici\u00f3n quede cerrada con un bolsillo) 126 pb (126)<br \/>\n<span style=\"color: #ff0000;\">31-48 hileras<\/span>. 126 pb (126)<br \/>\nLo llenamos poco a poco. Adjuntamos las manijas. Marcamos su ubicaci\u00f3n en el centro de los lados. Primero, como con el tercer dedo, tejemos juntos con los bucles del cuerpo, 7 pb en cada mango. El tercer dedo de la mano debe ser del lado del cuerpo.<br \/>\n<span style=\"color: #ff0000;\">49 hilera<\/span>. 7 pb junto con el primer mango, 55 pb, 7 pb junto con el segundo mango, 57 pb (126)<br \/>\n<span style=\"color: #ff0000;\">50 hilera<\/span>. tejemos a lo largo del per\u00edmetro con los bucles restantes de las manos 11 pb (primer mango), 55 pb, 11 pb (segundo mango), 57 pb (134)<br \/>\n<span style=\"color: #ff0000;\">51 hilera<\/span>. 134 pb (134)<br \/>\n<span style=\"color: #ff0000;\">52 hilera<\/span>. formar los hombros. En bol\u00edgrafos de 11 pb hacemos disminuciones ((dism, 1 pb)* 3 veces, dism), 55 pb, ((dism, 1 pb) 3 veces, dism), 57 pb (126)<br \/>\nDoblamos el cable en los hombros, juntamos los extremos y lo envolvemos con cinta adhesiva. Expande la punta hacia abajo. Seguimos tejiendo el cuerpo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3628 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cuerpo.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"779\" height=\"244\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cuerpo.jpg 779w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cuerpo-300x94.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cuerpo-768x241.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cuerpo-150x47.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cuerpo-750x235.jpg 750w\" sizes=\"auto, (max-width: 779px) 100vw, 779px\" \/><\/p>\n<p>Al aumentar o disminuir el n\u00famero de filas entre 53 y 76, puedes vincular diferentes minions<br \/>\n<span style=\"color: #ff0000;\">53-76 hileras<\/span>. 126 pb (126)<br \/>\n<span style=\"color: #ff0000;\">77 hilera<\/span>. (16 pb, dism)* 7 veces (119)<br \/>\n<span style=\"color: #ff0000;\">78-93 hileras<\/span>. 119 pb (119)<br \/>\n<span style=\"color: #ff0000;\">94 hilera<\/span>. (15 pb, dism)* 7 veces (112)<br \/>\nSeguimos rellenando con fibra. Apretado para que no queden arrugas ni desniveles.<br \/>\n<span style=\"color: #ff0000;\">95 hilera<\/span>. 112 pb (112)<br \/>\n<span style=\"color: #ff0000;\">96 hilera<\/span>. (14 pb, dism)* 7 veces (105)<br \/>\n<span style=\"color: #ff0000;\">97 hilera<\/span>. 105 pb (105)<br \/>\n<span style=\"color: #ff0000;\">98 hilera<\/span>. (13 pb, dism)* 7 veces (98)<br \/>\n<span style=\"color: #ff0000;\">99 hilera<\/span>. 98 pb (98)<br \/>\n<span style=\"color: #ff0000;\">100 hilera<\/span>. (12 pb, dism)* 7 veces (91)<br \/>\n<span style=\"color: #ff0000;\">101 hilera<\/span>. 91 pb (91)<br \/>\n<span style=\"color: #ff0000;\">102 hilera<\/span>. (11 pb, dism)* 7 veces (84)<br \/>\n<span style=\"color: #ff0000;\">103 hilera<\/span>. 84 pb (84)<br \/>\n<span style=\"color: #ff0000;\">104 hilera<\/span>. (10 pb, dism)* 7 veces (77)<br \/>\n<span style=\"color: #ff0000;\">105 hilera<\/span>. 77 pb (77)<br \/>\n<span style=\"color: #ff0000;\">106 hilera<\/span>. (9 pb, dism)* 7 veces (70)<br \/>\n<span style=\"color: #ff0000;\">107 hilera<\/span>. 70 pb (70)<br \/>\n<span style=\"color: #ff0000;\">108 hilera<\/span>. (8 pb, dism)* 7 veces (63)<br \/>\n<span style=\"color: #ff0000;\">109 hilera<\/span>. 63 pb (63)<br \/>\n<span style=\"color: #ff0000;\">110 hilera<\/span>. (7 pb, dism)* 7 veces (56)<br \/>\n<span style=\"color: #ff0000;\">111 hilera<\/span>. (6 pb, dism)* 7 veces (49)<br \/>\n<span style=\"color: #ff0000;\">112 hilera<\/span>. (5 pb, dism)* 7 veces (42)<br \/>\nEn este punto, es hora de pensar en tu peinado. Consulta las opciones en internet:<br \/>\n-Pelos separados por toda la cabeza;<br \/>\n-Los pelos de la coronilla en dos hileras (como el m\u00edo);<br \/>\n-Peque\u00f1o racimo en la parte superior de la cabeza.<br \/>\nSi desea la primera opci\u00f3n, puede comenzar a unir los pelos ahora. Corta el hilo negro en tiras. En un extremo del segmento, haz un nudo grande y \u00fanelo a la cabeza con una aguja o gancho. La segunda opci\u00f3n tambi\u00e9n se puede arreglar. Hice exactamente eso al principio. Pero luego cambi\u00e9 el hilo por uno m\u00e1s delgado y fij\u00e9 los hilos con solo nudos despu\u00e9s de cerrar el tejido. En el caso de la tercera opci\u00f3n, prepare previamente el paquete y aseg\u00farelo cuando tire de los \u00faltimos 7 bucles. Adem\u00e1s, cosa el paquete mientras lo une para que se sujete mejor.<br \/>\n<span style=\"color: #ff0000;\">113 hilera<\/span>. (4 pb, dism)* 7 veces (35)<br \/>\n<span style=\"color: #ff0000;\">114 hilera<\/span>. (3 pb, dism)* 7 veces (28)<br \/>\n<span style=\"color: #ff0000;\">115 hilera<\/span>. (2 pb, dism)* 7 veces (21)<br \/>\n<span style=\"color: #ff0000;\">116 hilera<\/span>. (1 pb, dism)* 7 veces (14)<br \/>\n<span style=\"color: #ff0000;\">117 hilera<\/span>. 7 dism (7)<br \/>\nAprietamos los bucles restantes, sujetamos la punta, la escondemos dentro del juguete.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3631 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"633\" height=\"196\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello.jpg 633w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello-300x93.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-cabello-150x46.jpg 150w\" sizes=\"auto, (max-width: 633px) 100vw, 633px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Delantal<\/span><\/h3>\n<p>Tejemos con hilo azul, ganchillo de 3 mm.<br \/>\nComencemos con el bolsillo delantero. Dejamos las paredes frontales de 50 bucles en el est\u00f3mago. Ahora tejemos la primera fila a lo largo de ellos (luego todo se teje en filas rotativas):<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. 50 pb (50)<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. lazo de elevaci\u00f3n (cad), 2 saltar, 40 pb, 2 saltar, 1 pb (46)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. cad, dism, 40 pb, dism, 1 pb (44)<br \/>\n<span style=\"color: #ff0000;\">4 hilera<\/span>. cad, dism, 38 pb, dism, 1 pb (42)<br \/>\n<span style=\"color: #ff0000;\">5 hilera<\/span>. cad, dism, 36 pb, dism, 1 pb (40)<br \/>\n<span style=\"color: #ff0000;\">6 hilera<\/span>. cad, dism, 34 pb, dism, 1 pb (38)<br \/>\n<span style=\"color: #ff0000;\">7 hilera<\/span>. cad, dism, 32 pb, dism, 1 pb (36)<br \/>\n<span style=\"color: #ff0000;\">8 hilera<\/span>. cad, dism, 30 pb, dism, 1 pb (34)<br \/>\n<span style=\"color: #ff0000;\">9 hilera<\/span>. cad, dism, 28 pb, dism, 1 pb (32)<br \/>\n<span style=\"color: #ff0000;\">10 hilera<\/span>. cad, dism, 26 pb, dism, 1 pb (30)<br \/>\n<span style=\"color: #ff0000;\">11 hilera<\/span>. cad, dism, 24 pb, dism, 1 pb (28)<br \/>\n<span style=\"color: #ff0000;\">12 hilera<\/span>. cad, dism, 22 pb, dism, 1 pb (26)<br \/>\n<span style=\"color: #ff0000;\">13 hilera<\/span>. cad, dism, 20 pb, dism, 1 pb (24)<br \/>\n<span style=\"color: #ff0000;\">14-32 hileras<\/span>. 24 pb (24)<br \/>\nPuedes atar los bordes de la pb si quieres.<br \/>\n<strong>Detr\u00e1s del centro de la espalda en el cintur\u00f3n, tambi\u00e9n recolectamos 24 pb, tejemos en filas rotativas:<\/strong><br \/>\n<span style=\"color: #ff0000;\">1-18 hileras<\/span>. 24 pb (24)<br \/>\nCorreas Tejemos 57 hileras de 4 pb. El n\u00famero de filas que tiene puede ser diferente. Pru\u00e9bate mientras tejes.<br \/>\nDecoramos el bolsillo delantero a lo largo del per\u00edmetro, la espalda y los tirantes del mono con hilo blanco. Tambi\u00e9n resalt\u00e9 el cintur\u00f3n con \u00e9l.<\/p>\n<h3><span style=\"color: #cc99ff;\">Bolsillo Peque\u00f1o<\/span><\/h3>\n<p>Recogemos una cadena de 15 bucles de aire. A continuaci\u00f3n, tejemos en filas rotativas:<br \/>\n<span style=\"color: #ff0000;\">1-10 hileras<\/span>. cad, 14 pb (15)<br \/>\n<span style=\"color: #ff0000;\">11 hilera<\/span>. cad, dism, 9 pb, dism, 1 pb (13)<br \/>\n<span style=\"color: #ff0000;\">12 hilera<\/span>. 13 pb (13)<br \/>\n<span style=\"color: #ff0000;\">13 hilera<\/span>. cad, dism, 7 pb, dism, 1 pb (11)<br \/>\nLos minions tienen un logo en el bolsillo. Puedes verlo en l\u00ednea. lo hicefieltro: c\u00edrculo negro D20 mm + letra G en fieltro azul. La letra est\u00e1 pegada al c\u00edrculo, el c\u00edrculo est\u00e1 pegado al bolsillo. Coser el bolsillo con hilos blancos. Ahora cosimos las correas con hilo blanco. A\u00f1ade botones al frente. S\u00f3lo hab\u00eda bucles en el cintur\u00f3n. Hice cuatro de ellos con cadenas de bucles de aire. Describir\u00e9 el proceso de crear exactamente mi versi\u00f3n. Pero puedes mirar las im\u00e1genes y elegir cualquier expresi\u00f3n facial para tu minion. Las partes principales ser\u00e1n las mismas, pero dependiendo de la expresi\u00f3n elegida, puede tener una ubicaci\u00f3n diferente del iris en el hemisferio (direcci\u00f3n de la mirada), el tama\u00f1o del p\u00e1rpado (mirada abierta, ojos entrecerrados, etc.), la presencia de un p\u00e1rpado inferior (mirada entrecerrada).<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3634\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-overalls-1.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"1006\" height=\"193\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-overalls-1.jpg 1006w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-overalls-1-300x58.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-overalls-1-768x147.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-overalls-1-150x29.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-overalls-1-750x144.jpg 750w\" sizes=\"auto, (max-width: 1006px) 100vw, 1006px\" \/><br \/>\n\u2800<br \/>\n<span style=\"color: #cc99ff;\">Ojos<\/span><\/h3>\n<p>Primero, tejemos todas las partes necesarias. El ojo consta de un hemisferio, una cubierta posterior, un iris (si el tama\u00f1o de un ojo seguro no le conviene) y un p\u00e1rpado. Empezamos con un hemisferio. Tejemos en blanco, gancho de 3 mm.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. 6 pb en AM (6)<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. 6 aum (12)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. (1 pb, aum)* 6 veces (18)<br \/>\n<span style=\"color: #ff0000;\">4 hilera<\/span>. (2 pb, aum)* 6 veces (24)<br \/>\n<span style=\"color: #ff0000;\">5 hilera<\/span>. (3 pb, aum)* 6 veces (30)<br \/>\n<span style=\"color: #ff0000;\">6 hilera<\/span>. (4 pb, aum)* 6 veces (36)<br \/>\n<span style=\"color: #ff0000;\">7 hilera<\/span>. (5 pb, aum)* 6 veces (42)<br \/>\n<span style=\"color: #ff0000;\">8 hilera<\/span>. (6 pb, aum)* 6 veces (48)<br \/>\n<span style=\"color: #ff0000;\">9-12 hileras<\/span>. 48 pb (48)<br \/>\nTejemos dos partes. Contraportada. Tejemos en blanco, gancho de 3 mm. Repetimos lo mismo de las filas 1 a 8. Tejemos dos partes. Dejamos la punta larga para coser. Tejemos los lirios en el color deseado (tengo marr\u00f3n) 6 pb en AM, 6 aum. Inserte el ojo en el centro del iris.<br \/>\n<strong>P\u00e1rpado<\/strong><br \/>\nTejer con hilo amarillo, ganchillo de 3 mm. El principio de tejer es como el de un pu\u00f1o, solo que en este caso restamos el n\u00famero de pb. Mi p\u00e1rpado ocupa aproximadamente 1\/4 del ojo. Para esta opci\u00f3n es suficiente una cadena de 18 pb. Si desea hacerlo m\u00e1s o menos, agregue \/ reste 6 bucles para que los dism \/ aum sean uniformes.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. recolectamos una cadena de 19 cad, comenzamos a tejer desde el tercer bucle desde el gancho 17 pb (18)<br \/>\n<span style=\"color: #ff0000;\">2 hilera<\/span>. cad, 17 pb (18)<br \/>\n<span style=\"color: #ff0000;\">3 hilera<\/span>. cad, dism, (1 pb, dism)* 5 veces (12)<br \/>\n<span style=\"color: #ff0000;\">4-5 hileras<\/span>. cad, 11 pb (12)<br \/>\n<span style=\"color: #ff0000;\">6 hilera<\/span>. cad, 5 dism, 1 pb (7)<br \/>\n<span style=\"color: #ff0000;\">7 hilera<\/span>. cad, 3 dism (4)<br \/>\nSujetamos el hilo, dejamos la punta para coser. Tejemos dos partes.<br \/>\n<strong>Recogemos los ojos.<\/strong><br \/>\nInstalamos el ojo seguro con el iris en el lugar correcto. Mi minion mira hacia arriba so\u00f1adoramente, por lo que la base del ojo se encuentra entre las filas 4 y 5. Cose los p\u00e1rpados. Cubrir ligeramente el iris del p\u00e1rpado a\u00f1ade enso\u00f1aci\u00f3n. Tenga cuidado de que los ojos sean sim\u00e9tricos (direcci\u00f3n de la mirada). Coser en la contraportada. Al final de la costura, llenamos el ojo.<br \/>\n<strong>Rect\u00e1ngulos restantes para el marco.<\/strong><br \/>\nTejemos con un hilo gris, gancho de 3 mm.<br \/>\n<span style=\"color: #ff0000;\">1 hilera<\/span>. recolectamos una cadena de 51 cad, tejemos desde el tercer bucle desde el gancho 49 pb (50)<br \/>\n<span style=\"color: #ff0000;\">2-15 hileras<\/span>. filas rotatorias cad, 49 pb (50)<br \/>\n<span style=\"color: #ff0000;\">16 hilera<\/span>. agregar protuberancias (BO) 7 pb, (BO, 4 pb)* 8 veces, 3 pb (50)<br \/>\nProtuberancia: el elemento se realiza sobre la base de 4 puntos altos, que se tejen en un punto con puntos bajos sin terminar, recogidos en un lazo en una parte superior com\u00fan.<br \/>\n<span style=\"color: #ff0000;\">17-20 hileras<\/span>. cad, 49 pb (50)<br \/>\nTejemos dos partes. Dejamos la punta larga para coser.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3637 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"1048\" height=\"448\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2.jpg 1048w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2-300x128.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2-1024x438.jpg 1024w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2-768x328.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2-150x64.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-2-750x321.jpg 750w\" sizes=\"auto, (max-width: 1048px) 100vw, 1048px\" \/><br \/>\n\u2800<br \/>\nDoblar por la mitad a lo largo, coser. Por otro lado, tambi\u00e9n hacemos una costura por simetr\u00eda. Ahora necesitamos una botella de pl\u00e1stico de 2 litros para insertar en el marco. Recorte un rect\u00e1ngulo, ins\u00e9rtelo en la parte tejida (para facilitar la inserci\u00f3n, redondee las esquinas en un lado de la tira), aj\u00fastelo en longitud (c\u00f3rtelo del lado redondeado), cosa la parte en un anillo. Probando en el ojo. Repetimos todo una vez m\u00e1s. Una vez que el marco est\u00e1 listo, probamos ambos ojos, fijamos su posici\u00f3n correcta en el marco y lo cosimos desde atr\u00e1s. Adem\u00e1s, los c\u00edrculos del marco deben ubicarse con costuras entre s\u00ed (no hay grumos). Preste atenci\u00f3n tambi\u00e9n al hecho de que el marco tiene diferentes extremos. El siguiente paso es coser los marcos al cuerpo. Los unimos (cosemos a lo largo de 4-5 pb). Correa restante Us\u00e9 una correa de 20 mm de ancho, pero puede atar el cord\u00f3n a la longitud que desee. Para unir el cord\u00f3n a las gafas, tejemos dos rect\u00e1ngulos con hilo gris 8 pb por 6 hileras. Dobla el rect\u00e1ngulo por la mitad a trav\u00e9s del tejido, inserta el extremo del cord\u00f3n y cose. Coser el lado opuesto al marco. Comprobamos la longitud. Tambi\u00e9n cosimos el otro extremo del cord\u00f3n en un rect\u00e1ngulo y lo unimos al marco en el otro lado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3640 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"998\" height=\"414\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos.jpg 998w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-300x124.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-768x319.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-150x62.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-ojos-750x311.jpg 750w\" sizes=\"auto, (max-width: 998px) 100vw, 998px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Montaje<\/span><\/h3>\n<p>As\u00ed pues, necesitamos fieltro de 1 mm de colores blanco, negro y rojo (si lo haces con la lengua), una plantilla de sonrisa, gel adhesivo Moment y un rotulador o rotulador de helio negro. Puede dibujar una plantilla de sonrisa usted mismo o traducirla desde la pantalla de su computadora. Agregu\u00e9 una foto de minions en el carrusel para ayudarte. Me dibuj\u00e9 a m\u00ed mismo, y ten\u00eda muchas opciones. En la foto hay tres finales, de las cuales eleg\u00ed la final.<br \/>\n<span style=\"color: #ff0000;\">1<\/span>. Recorta el contorno principal de fieltro negro.<br \/>\n<span style=\"color: #ff0000;\">2<\/span>. Aplique fieltro blanco encima, delinee el borde de la boca (el contorno es visible a trav\u00e9s del fieltro) y dibuje los dientes. Si tambi\u00e9n tienes dientes debajo, entonces repetimos lo mismo. No nos olvidemos de la simetr\u00eda. Separar.<br \/>\n<span style=\"color: #ff0000;\">3<\/span>. Recorta una tira delgada de fieltro rojo, coloca los dientes inferiores, haz un c\u00edrculo y dibuja un semic\u00edrculo en la parte superior. Separar.<br \/>\n<span style=\"color: #ff0000;\">4<\/span>. Probar todas las partes. Recortar y alinear los contornos.<br \/>\n<span style=\"color: #ff0000;\">5<\/span>. Primero pegamos los dientes sobre la base negra, luego la lengua.<br \/>\n<span style=\"color: #ff0000;\">6<\/span>. Con un bol\u00edgrafo o marcador de helio, seleccione los dientes, dibujando las l\u00edneas interdentales.<br \/>\n<span style=\"color: #ff0000;\">7<\/span>. Pegamos una sonrisa en el cuerpo a la altura requerida.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3643 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-delantal.jpg\" alt=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\" width=\"752\" height=\"348\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-delantal.jpg 752w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-delantal-300x139.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-delantal-150x69.jpg 150w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis-delantal-750x347.jpg 750w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><br \/>\n\u2800<br \/>\nEso es todo!<br \/>\nSi todav\u00eda le resulta dif\u00edcil, entonces simplemente puede cortar un trozo delgado de fieltro negro de la longitud y la forma requeridas y pegarlo.<br \/>\n\u2800<br \/>\nEso es todo. Felicidades !! \u00a1Tu minino est\u00e1 listo!<\/p>\n<h3><span style=\"color: #cc99ff;\">Descargar Patr\u00f3n PDF<\/span><br \/>\n<a href=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Paso-a-Paso-Minion-Rush-PDF-Amigurumi-Patron-Gratis.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1517\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/dow.png\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Hola a todos amigos, Hoy os traigo un patr\u00f3n de amigurumi muy especial. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El patr\u00f3n de amigurumi gratuito es un poco largo, por lo que puede no ser ideal para principiantes. Patr\u00f3n de amigurumi Minion Rush, gracias a las instrucciones detalladas paso a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,94],"tags":[],"class_list":["post-3614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-munecas","category-personajes-de-cuento-de-hadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis - 500+ PDF Passo a Passo Amigurumi Receitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis - 500+ PDF Passo a Passo Amigurumi Receitas\" \/>\n<meta property=\"og:description\" content=\"Hola a todos amigos, Hoy os traigo un patr\u00f3n de amigurumi muy especial. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El patr\u00f3n de amigurumi gratuito es un poco largo, por lo que puede no ser ideal para principiantes. Patr\u00f3n de amigurumi Minion Rush, gracias a las instrucciones detalladas paso a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/\" \/>\n<meta property=\"og:site_name\" content=\"500+ PDF Passo a Passo Amigurumi Receitas\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T19:05:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-07T11:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/amigurumireceitas.com\/#organization\",\"name\":\"Amigurumi Receitas\",\"url\":\"https:\/\/amigurumireceitas.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png\",\"contentUrl\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png\",\"width\":500,\"height\":500,\"caption\":\"Amigurumi Receitas\"},\"image\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amigurumireceitas.com\/#website\",\"url\":\"https:\/\/amigurumireceitas.com\/\",\"name\":\"500+ PDF Passo a Passo Amigurumi Receitas\",\"description\":\"300+ PDF Amigurumi Patr\u00f3n Gratis\",\"publisher\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/amigurumireceitas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#primaryimage\",\"url\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg\",\"contentUrl\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg\",\"width\":350,\"height\":350,\"caption\":\"Crochet Minion Rush Free PDF Amigurumi Pattern\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#webpage\",\"url\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/\",\"name\":\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis - 500+ PDF Passo a Passo Amigurumi Receitas\",\"isPartOf\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#primaryimage\"},\"datePublished\":\"2022-01-11T19:05:04+00:00\",\"dateModified\":\"2022-06-07T11:27:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/amigurumireceitas.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#webpage\"},\"author\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16\"},\"headline\":\"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis\",\"datePublished\":\"2022-01-11T19:05:04+00:00\",\"dateModified\":\"2022-06-07T11:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#webpage\"},\"wordCount\":3107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg\",\"articleSection\":[\"Mu\u00f1ecas\",\"Personajes de cuento de hadas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/amigurumireceitas.com\",\"admin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis - 500+ PDF Passo a Passo Amigurumi Receitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/","og_locale":"es_ES","og_type":"article","og_title":"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis - 500+ PDF Passo a Passo Amigurumi Receitas","og_description":"Hola a todos amigos, Hoy os traigo un patr\u00f3n de amigurumi muy especial. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El patr\u00f3n de amigurumi gratuito es un poco largo, por lo que puede no ser ideal para principiantes. Patr\u00f3n de amigurumi Minion Rush, gracias a las instrucciones detalladas paso a [&hellip;]","og_url":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/","og_site_name":"500+ PDF Passo a Passo Amigurumi Receitas","article_published_time":"2022-01-11T19:05:04+00:00","article_modified_time":"2022-06-07T11:27:43+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/amigurumireceitas.com\/#organization","name":"Amigurumi Receitas","url":"https:\/\/amigurumireceitas.com\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/","url":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png","contentUrl":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png","width":500,"height":500,"caption":"Amigurumi Receitas"},"image":{"@id":"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/amigurumireceitas.com\/#website","url":"https:\/\/amigurumireceitas.com\/","name":"500+ PDF Passo a Passo Amigurumi Receitas","description":"300+ PDF Amigurumi Patr\u00f3n Gratis","publisher":{"@id":"https:\/\/amigurumireceitas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amigurumireceitas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#primaryimage","url":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg","contentUrl":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg","width":350,"height":350,"caption":"Crochet Minion Rush Free PDF Amigurumi Pattern"},{"@type":"WebPage","@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#webpage","url":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/","name":"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis - 500+ PDF Passo a Passo Amigurumi Receitas","isPartOf":{"@id":"https:\/\/amigurumireceitas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#primaryimage"},"datePublished":"2022-01-11T19:05:04+00:00","dateModified":"2022-06-07T11:27:43+00:00","breadcrumb":{"@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amigurumireceitas.com\/es\/"},{"@type":"ListItem","position":2,"name":"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis"}]},{"@type":"Article","@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#article","isPartOf":{"@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#webpage"},"author":{"@id":"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16"},"headline":"Paso a Paso Minion Rush PDF Amigurumi Patr\u00f3n Gratis","datePublished":"2022-01-11T19:05:04+00:00","dateModified":"2022-06-07T11:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#webpage"},"wordCount":3107,"commentCount":0,"publisher":{"@id":"https:\/\/amigurumireceitas.com\/#organization"},"image":{"@id":"https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#primaryimage"},"thumbnailUrl":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/01\/Crochet-Minion-Rush-Free-PDF-Amigurumi-Pattern-2.jpg","articleSection":["Mu\u00f1ecas","Personajes de cuento de hadas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amigurumireceitas.com\/es\/paso-a-paso-minion-rush-pdf-amigurumi-patron-gratis\/#respond"]}]},{"@type":"Person","@id":"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amigurumireceitas.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/amigurumireceitas.com","admin"]}]}},"_links":{"self":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts\/3614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/comments?post=3614"}],"version-history":[{"count":5,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts\/3614\/revisions"}],"predecessor-version":[{"id":26768,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts\/3614\/revisions\/26768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/media\/3541"}],"wp:attachment":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/media?parent=3614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/categories?post=3614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/tags?post=3614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}