{"id":29691,"date":"2022-06-22T19:42:17","date_gmt":"2022-06-22T18:42:17","guid":{"rendered":"https:\/\/amigurumireceitas.com\/?p=29691"},"modified":"2022-06-22T19:42:17","modified_gmt":"2022-06-22T18:42:17","slug":"amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso","status":"publish","type":"post","link":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/","title":{"rendered":"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29694 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"1280\" height=\"720\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso.jpg 1280w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-300x169.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-1024x576.jpg 1024w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-768x432.jpg 768w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-750x422.jpg 750w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-1140x641.jpg 1140w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Saludos amigos, hoy trabajaremos con ustedes el patr\u00f3n amigurumi del cachorro de tigre de peluche a crochet. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El tama\u00f1o final del <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/amigurumireceitas.com\/es\/category\/tigre\/\">amigurumi tigre<\/a><\/span><\/strong> de ganchillo ser\u00e1 de 30 cm. Para hacer un tigre de ganchillo tan hermoso, el dise\u00f1ador utiliz\u00f3 hilo de felpa Himalayan Dolphin Baby y un ganchillo de 4 mm. Gracias por visitar nuestra web amigurumireceitas.com.\u00a0 Las piernas y el cuerpo del tigre de ganchillo se tejen como una sola pieza, las partes restantes se arreglan m\u00e1s tarde. A continuaci\u00f3n se muestra una explicaci\u00f3n detallada <strong>paso a paso<\/strong> del patr\u00f3n de amigurumi. Ahora te invito a las instrucciones del patr\u00f3n gratis. Feliz semana para ti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29697 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-1.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"600\" height=\"800\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-1.jpg 600w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-1-225x300.jpg 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2><span style=\"color: #cc99ff;\">Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso<\/span><\/h2>\n<p><strong>Dise\u00f1ador:<\/strong> <a href=\"https:\/\/www.instagram.com\/happytoys_milena\/\" rel=\"nofollow\"><span style=\"color: #cc99ff;\">happytoys_milena<\/span><\/a><\/p>\n<h3><span style=\"color: #cc99ff;\">Materiales<\/span><\/h3>\n<p>\u2022 Hilo de felpa Himalaya Dolphin Baby 1-1,5 ovillos del color principal y 0,5 ovillos de color blanco y algo de negro. O cualquier otro hilo<br \/>\n\u2022 Hilo blanco Alize Softy solo un poco para la garganta<br \/>\n\u2022 Gancho #4mm, #3.5mm o #4.5mm (Yo uso #4)<br \/>\n\u2022 Gancho No. 2.5mm para la garganta<br \/>\n\u2022 Un par de ojos de vidrio de 16 mm (si no hay ojos de vidrio, puede usar pl\u00e1stico)<br \/>\n\u2022 Hilo de algod\u00f3n negro<br \/>\n\u2022 Momento de pegamento CRISTAL<br \/>\n\u2022 Ca\u00f1o 13*15mm<br \/>\n\u2022 Tijeras<br \/>\n\u2022 Aguja larga<br \/>\n\u2022 Relleno (fibra hueca, bolas sint\u00e9ticas, etc.)<\/p>\n<h3><span style=\"color: #cc99ff;\">Abreviaturas<\/span><\/h3>\n<p><span style=\"color: #ff0000;\">AM<\/span> \u2013 anillo m\u00e1gico<br \/>\n<span style=\"color: #ff0000;\">Cad<\/span> \u2013 cadeneta<br \/>\n<span style=\"color: #ff0000;\">Pb<\/span> \u2013 punto bajo<br \/>\n<span style=\"color: #ff0000;\">Mpa<\/span> \u2013 medio punto alto o punto media vareta<br \/>\n<span style=\"color: #ff0000;\">Pa<\/span> \u2013 punto alto o punto vareta<br \/>\n<span style=\"color: #ff0000;\">Pc<\/span>&#8211; punto enano, punto raso<br \/>\n<span style=\"color: #ff0000;\">Aum<\/span>&#8211; aumento en punto bajo<br \/>\n<span style=\"color: #ff0000;\">Dism<\/span>&#8211; Disminuci\u00f2n<br \/>\n<span style=\"color: #ff0000;\">BLO<\/span>&#8211; medio punto o punto bajo canal\u00e9 tomando s\u00f2lo la hebra de atras o punto bajo por backloop<br \/>\n<span style=\"color: #ff0000;\">FLO<\/span>&#8211; medio punto o punto bajo canal\u00e9 tomando s\u00f2lo la hebra de adelante<br \/>\n<span style=\"color: #ff0000;\">V<\/span>\u2013 vuelta(s)<\/p>\n<h3><span style=\"color: #cc99ff;\">Cabeza<\/span><\/h3>\n<p>(El color del hilo es adicional (blanco), gancho No. 4 mm)<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 5cad, desde el 2\u00b0 bucle desde el ganchillo aum, 2pb, en el \u00faltimo bucle 4pb, en el reverso de la cadena 2pb, aum (12pb)<br \/>\n<span style=\"color: #ff0000;\">V 2<\/span>. 2aum, 2pb, 4aum, 2pb, 2aum (20pb)<br \/>\n<span style=\"color: #ff0000;\">V 3<\/span>. (1pb, aum)*2, 2pb, (1pb, aum)*4, 2pb, (1pb, aum)*2 (28pb)<br \/>\n<span style=\"color: #ff0000;\">V 4-5<\/span>. 28pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 6<\/span>. (3pb, aum)*7 (35pb)<br \/>\n<span style=\"color: #ff0000;\">V 7<\/span>. 6pb , (ponemos dos marcapuntos adicionales en el primer pb del primer aumento y en el \u00faltimo pb del sexto aumento: marcapuntos para el ojo), 6 aum, 14 pb, aum, 8 pb (42 pb)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29700 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cabeza2.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"554\" height=\"591\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cabeza2.jpg 554w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cabeza2-281x300.jpg 281w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><\/p>\n<p><span style=\"color: #ff0000;\">V 8<\/span>. (5pb, aum)*7 (49pb)<br \/>\n<span style=\"color: #ff0000;\">V 9<\/span>. 49pb<br \/>\n<span style=\"color: #ff0000;\">V 10<\/span>. 39pb, cambiar hilo a hilo principal, 10pb (49pb)<br \/>\nNo tejemos hasta el final de la fila 10pb, cambiamos el hilo al principal. Hacemos esto para que la transici\u00f3n de color est\u00e9 en la parte inferior del hocico.<br \/>\n<span style=\"color: #ff0000;\">V 11-13<\/span>. 49pb (3 filas)<br \/>\n<span style=\"color: #ff0000;\">V 14<\/span>. (5pb, dism)*7 (42pb)<br \/>\nFijamos los ojos entre 7 y 8 filas, donde hay marcadores adicionales. Abrochamos la nariz en el medio entre 2 y 3 filas.<br \/>\n<span style=\"color: #ff0000;\">V 15<\/span>. 2pb, dism, (4pb, dism)*6, 2pb (35pb)<br \/>\n<span style=\"color: #ff0000;\">V 16<\/span>. (3pb, dism)*7 (28pb)<br \/>\n<span style=\"color: #ff0000;\">V 17<\/span>. 1pb, dism, (2pb, dism)*6, 1pb (21pb)<br \/>\n<span style=\"color: #ff0000;\">V 18<\/span>. (1pb, dism)*7 (14pb)<br \/>\n<span style=\"color: #ff0000;\">V 19<\/span>. 7dism<br \/>\nCortar el hilo, cerrar el agujero, esconder la punta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29703 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cabeza1.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"588\" height=\"390\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cabeza1.jpg 588w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cabeza1-300x199.jpg 300w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Puente de la Nariz<\/span><\/h3>\n<p>(Color del hilo principal, gancho No. 4)<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 6cad, desde el segundo bucle desde el gancho 5pb, cad, gire (5pb)<br \/>\n<span style=\"color: #ff0000;\">V 2<\/span>. 5pb<br \/>\n<span style=\"color: #ff0000;\">V 3<\/span>. 2pb, dism, 1pb (4pb)<br \/>\n<span style=\"color: #ff0000;\">V 4<\/span>. 4pb<br \/>\n<span style=\"color: #ff0000;\">V 5<\/span>. 1pb, dism, 1pb (3pb)<br \/>\n<span style=\"color: #ff0000;\">V 6<\/span>. 3pb<br \/>\n<span style=\"color: #ff0000;\">V 7<\/span>. 1pb, dism (2pb)<br \/>\n<span style=\"color: #ff0000;\">V 8<\/span>. 2pb<br \/>\nSin cadena, comenzamos a atar la pieza. Atamos en tres lados (lado, arriba, lado), sin atar la \u00faltima octava fila. Hacemos adiciones en las esquinas.<br \/>\nCortar el hilo, sujetar, ocultar la punta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29706 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-hocico.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"454\" height=\"460\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-hocico.jpg 454w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-hocico-296x300.jpg 296w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-hocico-75x75.jpg 75w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/p>\n<p>Coser en el puente. Colocamos la pieza entre 10 filas (cambio de hilo) y 3 filas, hasta el pico. Hacemos un bozal. Necesitaremos hilo de felpa negro, hilo de felpa blanco, hilo de algod\u00f3n negro.<br \/>\nPara empezar, atamos el hocico con felpa negra, donde se cambi\u00f3 el hilo. Desde el puente de la nariz, en ambas direcciones, contamos 14 pb.<br \/>\nAtamos el lado izquierdo: 14 pc en la cabeza y 3 pc en el puente de la nariz.<br \/>\nAtamos el lado derecho: 3 pc en el puente de la nariz y 14 pc en la cabeza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29709 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-4.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"482\" height=\"263\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-4.jpg 482w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-4-300x164.jpg 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/p>\n<p>Bordamos los p\u00e1rpados con felpa negra, manchas en el hocico, manchas en el puente de la nariz, rayas en las mejillas.<br \/>\nCon algod\u00f3n negro bordamos las cejas y el medio entre las mejillas.<br \/>\nBordamos manchas en el puente de la nariz con felpa blanca.<\/p>\n<h3><span style=\"color: #cc99ff;\">Boca<\/span><\/h3>\n<p>(El color del hilo es blanco, gancho No. 4 mm)<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 2cad, en el 2do bucle desde el gancho 3 mpa, 2cad, pc.<br \/>\nCortamos el hilo, dejando un extremo largo para coser.<br \/>\nCoser la boca al hocico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29712 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-boca.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"249\" height=\"319\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-boca.jpg 249w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-boca-234x300.jpg 234w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Orejas<\/span><\/h3>\n<p>(El color del hilo es blanco, gancho No. 4 mm)<br \/>\n2 partes (ojal interior)<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 5pb en AM, cad, girar<br \/>\n<span style=\"color: #ff0000;\">V 2<\/span>. 2pb, en un bucle (pb, mpa, pb), 2pb, cad, girar (7pb)<br \/>\n<span style=\"color: #ff0000;\">V 3<\/span>. aum, 2pb, en un bucle (pb, mpa, pb), 2 pb, aum (11pb)<br \/>\n<span style=\"color: #ff0000;\">V 4<\/span>. aum, 4pb, en un bucle (pb, mpa, pb), 4pb, aum (15pb)<br \/>\nCortar el hilo, sujetar, ocultar la punta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29715 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas1.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"340\" height=\"335\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas1.jpg 340w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas1-300x296.jpg 300w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas1-75x75.jpg 75w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/p>\n<p>Del mismo modo, tejemos el ojo exterior en 2 partes con el ganchillo n\u00ba 4, del color del hilo principal.<br \/>\nCortamos el hilo, lo sujetamos, ocultamos la punta.<br \/>\nJunta 2 piezas. Aplicamos la parte blanca a la parte principal, para que sus v\u00e9rtices (pb, mpa, pb) coincidan. Atamos pb negro hilo de felpa, en la parte superior tejemos 3 pb en un bucle.<br \/>\nCoser las orejas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29718 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas2.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"309\" height=\"201\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas2.jpg 309w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-orejas2-300x195.jpg 300w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Cola<\/span><\/h3>\n<p>(El color del hilo es negro, gancho No. 4 mm)<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 6pb en AM<br \/>\n<span style=\"color: #ff0000;\">V 2<\/span>. 6aum (12pb)<br \/>\n<span style=\"color: #ff0000;\">V 3-4<\/span>. 12pb (2 filas)<br \/>\nCambiar el hilo al principal<br \/>\n<span style=\"color: #ff0000;\">V 5<\/span>. (4pb, dism)*2 (10pb)<br \/>\n<span style=\"color: #ff0000;\">V 6-10<\/span>. 10pb (5 filas)<br \/>\n<span style=\"color: #ff0000;\">V 11<\/span>. 8pb, dism (9pb)<br \/>\n<span style=\"color: #ff0000;\">V 12-16<\/span>. 9pb (5 filas)<br \/>\nRellenamos la cola hasta la fila 13.<br \/>\n<span style=\"color: #ff0000;\">V 17<\/span>. 7pb, dism (8pb)<br \/>\n<span style=\"color: #ff0000;\">V 18-20<\/span>. 8pb (3 filas)<br \/>\nDobla la parte por la mitad y teje 4pb juntos. Corta el hilo, esconde la punta. Tomamos un hilo de felpa negro y bordamos rayas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29721 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"327\" height=\"428\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola.jpg 327w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola-229x300.jpg 229w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Piernas y Cuerpo<\/span><\/h3>\n<p>(Color de hilo opcional, gancho No. 4mm)<br \/>\nPierna izquierda<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 6pb en AM<br \/>\n<span style=\"color: #ff0000;\">V 2<\/span>. 6aum (12pb)<br \/>\n<span style=\"color: #ff0000;\">V 3<\/span>. (1pb, aum)*6 (18pb)<br \/>\n<span style=\"color: #ff0000;\">V 4<\/span>. (2pb, aum)*6 (24pb)<br \/>\n<span style=\"color: #ff0000;\">V 5-6<\/span>. 24pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 7<\/span>. 1pb, 6dism, 11pb (18pb)<br \/>\n<span style=\"color: #ff0000;\">V 8<\/span>. 2pb, dism, 1pb, dism, 5pb, (cambio de hilo a hilo principal), 6pb (16pb)<br \/>\n<span style=\"color: #ff0000;\">V 9-15<\/span>. 16pb (7 filas)<br \/>\n<span style=\"color: #ff0000;\">V 16<\/span>. filas incompleta, 8pb, pc.<br \/>\nCorta el hilo, esconde la punta. Tejemos la segunda pierna de la misma manera hasta la fila 15 inclusive. Aqu\u00ed empezamos el cuerpo:<br \/>\n<span style=\"color: #ff0000;\">V 16<\/span>. (Pierna derecha), 3pb, 2cad, conectar la pierna derecha a la izquierda, tejer el pb en el pc de la pierna izquierda. Seguimos tejiendo en la pierna izquierda., 16pb, aum, 2pb en cad, aum, 13pb (40pb)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29724 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola2.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"396\" height=\"248\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola2.jpg 396w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola2-300x188.jpg 300w\" sizes=\"auto, (max-width: 396px) 100vw, 396px\" \/><\/p>\n<p><span style=\"color: #ff0000;\">V 17<\/span>. (9pb, aum)*4 (44pb)<br \/>\n<span style=\"color: #ff0000;\">V 18-19<\/span>. 44pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 20<\/span>. Tejemos una cola, 2pb, 4pb cuerpo + cola, 38pb (44pb)<br \/>\n<span style=\"color: #ff0000;\">V 21<\/span>. 44pb<br \/>\n<span style=\"color: #ff0000;\">V 22<\/span>. (9pb, dism)*4 (40pb)<br \/>\n<span style=\"color: #ff0000;\">V 23-25<\/span>. 40pb (3 filas)<br \/>\n<span style=\"color: #ff0000;\">V 26<\/span>. (8pb, dism)*4 (36pb)<br \/>\n<span style=\"color: #ff0000;\">V 27-28<\/span>. 36pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 29<\/span>. (4pb, dism)*6 (30pb)<br \/>\n<span style=\"color: #ff0000;\">V 30-31<\/span>. 30pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 32<\/span>. (3pb, dism)*6 (24pb)<br \/>\n<span style=\"color: #ff0000;\">V 33-34<\/span>. 24pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 35<\/span>. (2pb, dism)*6 (18pb)<br \/>\n<span style=\"color: #ff0000;\">V 36<\/span>. 18pb<br \/>\nCortamos el hilo, lo sujetamos, ocultamos la punta.<br \/>\nCosemos en la cabeza. Bordamos rayas con hilo de felpa negro: en las piernas, en los costados, en la espalda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29727 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola1.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"480\" height=\"629\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola1.jpg 480w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cola1-229x300.jpg 229w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Brazos (Hacer 2)<\/span><\/h3>\n<p>(Color de hilo opcional, gancho No. 4mm)<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 6pb en AM<br \/>\n<span style=\"color: #ff0000;\">V 2<\/span>. 6aum (12pb)<br \/>\n<span style=\"color: #ff0000;\">V 3<\/span>. (1pb, aum)*6 (18pb)<br \/>\n<span style=\"color: #ff0000;\">V 4<\/span>. 18pb<br \/>\n<span style=\"color: #ff0000;\">V 5<\/span>. 1pb, 4dism, 9pb (14pb)<br \/>\nCambiar el hilo al principal<br \/>\n<span style=\"color: #ff0000;\">V 6<\/span>. 1pb, 2dism, 9pb (12pb)<br \/>\n<span style=\"color: #ff0000;\">V 7-17<\/span>. 12pb (7 filas)<br \/>\n<span style=\"color: #ff0000;\">V 18<\/span>. (2pb, dism)*3 (9pb)<br \/>\nRellenamos la pieza por la mitad. Doblamos nuestra parte por la mitad y tejemos 4pb para ambas paredes (juntas) \u2013 para el mango derecho. Para la izquierda, tejer 1 pb adicionalmente, tambi\u00e9n doblar por la mitad y tejer 4 pb juntos. Bordamos rayas de felpa negra. Mira la foto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29730 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-brazos.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"264\" height=\"305\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-brazos.jpg 264w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-brazos-260x300.jpg 260w\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" \/><\/p>\n<h3><span style=\"color: #cc99ff;\">Cofre<\/span><\/h3>\n<p>(El color del hilo es blanco, hilo Alize Softy, gancho No. 2.5mm)<br \/>\nTejemos en filas rotativas.<br \/>\n<span style=\"color: #ff0000;\">V 1<\/span>. 10cad, desde el segundo bucle desde el gancho 9pb, cad, girar<br \/>\n<span style=\"color: #ff0000;\">V 2-3<\/span>. 9pb (2 filas)<br \/>\n<span style=\"color: #ff0000;\">V 4<\/span>. aum, 7pb, aum (11pb)<br \/>\n<span style=\"color: #ff0000;\">V 5<\/span>. 11pb<br \/>\n<span style=\"color: #ff0000;\">V 6<\/span>. aum, 9pb, aum (13pb)<br \/>\n<span style=\"color: #ff0000;\">V 7-10<\/span>. 13pb (4 filas)<br \/>\n<span style=\"color: #ff0000;\">V 11<\/span>. dism, 9pb, dism (11pb)<br \/>\n<span style=\"color: #ff0000;\">V 12<\/span>. 11pb<br \/>\n<span style=\"color: #ff0000;\">V 13<\/span>. dism, 7pb, dism (9pb)<br \/>\n<span style=\"color: #ff0000;\">V 14<\/span>. 9pb<br \/>\n<span style=\"color: #ff0000;\">V 15<\/span>. dism, 5pb, dism (7pb)<br \/>\n<span style=\"color: #ff0000;\">V 16<\/span>. 7pb<br \/>\n<span style=\"color: #ff0000;\">V 17<\/span>. dism, 3pb, dism (5pb)<br \/>\n<span style=\"color: #ff0000;\">V 18<\/span>. dism, 1pb, dism (3pb)<br \/>\n<span style=\"color: #ff0000;\">V 19<\/span>. dism from 3pb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29733 aligncenter\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cofre.jpg\" alt=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\" width=\"504\" height=\"325\" srcset=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cofre.jpg 504w, https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso-cofre-300x193.jpg 300w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/p>\n<p>Luego, atamos pb en un c\u00edrculo, haciendo incrementos en las vueltas. Deja un extremo largo para coser.<br \/>\nCoser en el pecho y los brazos.<\/p>\n<h3><span style=\"color: #cc99ff;\">Descargar Patr\u00f3n PDF<\/span><br \/>\n<a href=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Amigurumi-Bebe-Tigre-PDF-Patron-Gratis-Paso-a-Paso.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1517\" src=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/dow.png\" alt=\"dow\" width=\"150\" height=\"150\" \/><\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Saludos amigos, hoy trabajaremos con ustedes el patr\u00f3n amigurumi del cachorro de tigre de peluche a crochet. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El tama\u00f1o final del amigurumi tigre de ganchillo ser\u00e1 de 30 cm. Para hacer un tigre de ganchillo tan hermoso, el dise\u00f1ador utiliz\u00f3 hilo de felpa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110],"tags":[],"class_list":["post-29691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tigre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso - 500+ PDF Passo a Passo Amigurumi Receitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso - 500+ PDF Passo a Passo Amigurumi Receitas\" \/>\n<meta property=\"og:description\" content=\"Saludos amigos, hoy trabajaremos con ustedes el patr\u00f3n amigurumi del cachorro de tigre de peluche a crochet. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El tama\u00f1o final del amigurumi tigre de ganchillo ser\u00e1 de 30 cm. Para hacer un tigre de ganchillo tan hermoso, el dise\u00f1ador utiliz\u00f3 hilo de felpa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/\" \/>\n<meta property=\"og:site_name\" content=\"500+ PDF Passo a Passo Amigurumi Receitas\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-22T18:42:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/amigurumireceitas.com\/#organization\",\"name\":\"Amigurumi Receitas\",\"url\":\"https:\/\/amigurumireceitas.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png\",\"contentUrl\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png\",\"width\":500,\"height\":500,\"caption\":\"Amigurumi Receitas\"},\"image\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amigurumireceitas.com\/#website\",\"url\":\"https:\/\/amigurumireceitas.com\/\",\"name\":\"500+ PDF Passo a Passo Amigurumi Receitas\",\"description\":\"300+ PDF Amigurumi Patr\u00f3n Gratis\",\"publisher\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/amigurumireceitas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#primaryimage\",\"url\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg\",\"contentUrl\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg\",\"width\":1140,\"height\":760,\"caption\":\"Crochet Baby Tiger PDF Amigurumi Free Pattern\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#webpage\",\"url\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/\",\"name\":\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso - 500+ PDF Passo a Passo Amigurumi Receitas\",\"isPartOf\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#primaryimage\"},\"datePublished\":\"2022-06-22T18:42:17+00:00\",\"dateModified\":\"2022-06-22T18:42:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/amigurumireceitas.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#webpage\"},\"author\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16\"},\"headline\":\"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso\",\"datePublished\":\"2022-06-22T18:42:17+00:00\",\"dateModified\":\"2022-06-22T18:42:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#webpage\"},\"wordCount\":1371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/amigurumireceitas.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg\",\"articleSection\":[\"Tigre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/amigurumireceitas.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/amigurumireceitas.com\",\"admin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso - 500+ PDF Passo a Passo Amigurumi Receitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/","og_locale":"es_ES","og_type":"article","og_title":"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso - 500+ PDF Passo a Passo Amigurumi Receitas","og_description":"Saludos amigos, hoy trabajaremos con ustedes el patr\u00f3n amigurumi del cachorro de tigre de peluche a crochet. En primer lugar, me gustar\u00eda dar las gracias al propietario del patr\u00f3n. El tama\u00f1o final del amigurumi tigre de ganchillo ser\u00e1 de 30 cm. Para hacer un tigre de ganchillo tan hermoso, el dise\u00f1ador utiliz\u00f3 hilo de felpa [&hellip;]","og_url":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/","og_site_name":"500+ PDF Passo a Passo Amigurumi Receitas","article_published_time":"2022-06-22T18:42:17+00:00","og_image":[{"width":1140,"height":760,"url":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/amigurumireceitas.com\/#organization","name":"Amigurumi Receitas","url":"https:\/\/amigurumireceitas.com\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/","url":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png","contentUrl":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2021\/12\/Simple-Minimalist-Yarn-and-Knitting-Needles-Logo-1.png","width":500,"height":500,"caption":"Amigurumi Receitas"},"image":{"@id":"https:\/\/amigurumireceitas.com\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/amigurumireceitas.com\/#website","url":"https:\/\/amigurumireceitas.com\/","name":"500+ PDF Passo a Passo Amigurumi Receitas","description":"300+ PDF Amigurumi Patr\u00f3n Gratis","publisher":{"@id":"https:\/\/amigurumireceitas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amigurumireceitas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#primaryimage","url":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg","contentUrl":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg","width":1140,"height":760,"caption":"Crochet Baby Tiger PDF Amigurumi Free Pattern"},{"@type":"WebPage","@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#webpage","url":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/","name":"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso - 500+ PDF Passo a Passo Amigurumi Receitas","isPartOf":{"@id":"https:\/\/amigurumireceitas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#primaryimage"},"datePublished":"2022-06-22T18:42:17+00:00","dateModified":"2022-06-22T18:42:17+00:00","breadcrumb":{"@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amigurumireceitas.com\/es\/"},{"@type":"ListItem","position":2,"name":"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso"}]},{"@type":"Article","@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#article","isPartOf":{"@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#webpage"},"author":{"@id":"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16"},"headline":"Amigurumi Beb\u00e9 Tigre PDF Patr\u00f3n Gratis Paso a Paso","datePublished":"2022-06-22T18:42:17+00:00","dateModified":"2022-06-22T18:42:17+00:00","mainEntityOfPage":{"@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#webpage"},"wordCount":1371,"commentCount":0,"publisher":{"@id":"https:\/\/amigurumireceitas.com\/#organization"},"image":{"@id":"https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#primaryimage"},"thumbnailUrl":"https:\/\/amigurumireceitas.com\/wp-content\/uploads\/2022\/06\/Crochet-Baby-Tiger-PDF-Amigurumi-Free-Pattern-2.jpg","articleSection":["Tigre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amigurumireceitas.com\/es\/amigurumi-bebe-tigre-pdf-patron-gratis-paso-a-paso\/#respond"]}]},{"@type":"Person","@id":"https:\/\/amigurumireceitas.com\/#\/schema\/person\/cc3392fc3c35f4547dc27c2b40bb3c16","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amigurumireceitas.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe522568a109111131ca7d9dfb6e3a4840098ff9f1774eedefa51d65a230b732?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/amigurumireceitas.com","admin"]}]}},"_links":{"self":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts\/29691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/comments?post=29691"}],"version-history":[{"count":3,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts\/29691\/revisions"}],"predecessor-version":[{"id":29740,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/posts\/29691\/revisions\/29740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/media\/29510"}],"wp:attachment":[{"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/media?parent=29691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/categories?post=29691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigurumireceitas.com\/es\/wp-json\/wp\/v2\/tags?post=29691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}